{"id":160,"date":"2022-01-20T14:50:28","date_gmt":"2022-01-20T13:50:28","guid":{"rendered":"https:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/?p=160"},"modified":"2022-02-17T14:47:27","modified_gmt":"2022-02-17T13:47:27","slug":"sonerien-du-50-ans-de-festou-noz-1972-2022","status":"publish","type":"post","link":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/sonerien-du-50-ans-de-festou-noz-1972-2022\/","title":{"rendered":"Sonerien Du : 50 ans de festo\u00f9-noz (1972-2022)"},"content":{"rendered":"\n<p><strong>Auteur :<\/strong> Gilles Simon<\/p>\n\n\n\n<p><strong>Cr\u00e9\u00e9 en 1972 au sein du cercle celtique de Pont&nbsp;l\u2019Abb\u00e9, Sonerien&nbsp;Du est le plus vieux groupe de musique bretonne toujours en activit\u00e9. M\u00e9langeant, d\u00e8s le d\u00e9but, sonorit\u00e9s traditionnelles et contemporaines avec \u00e9nergie, il se caract\u00e9rise aussi par une \u00e9volution continue de la composition du groupe qui a eu, en tout, pas moins de 23&nbsp;musiciens \u00ab&nbsp;permanents&nbsp;\u00bb.<\/strong><\/p>\n\n\n\n<p>C\u2019est en septembre 1972 que le sonneur Yann-Korentin&nbsp;Ar&nbsp;Gall (27&nbsp;ans) fonde le groupe Sonerien&nbsp;Du avec son comp\u00e8re sonneur Dani&nbsp;Tanneau (27&nbsp;ans), le chanteur-guitariste Raymond&nbsp;Riou (22&nbsp;ans) et l\u2019accord\u00e9oniste Gilles&nbsp;Rolland (16&nbsp;ans). Tous sont n\u00e9s \u00e0 Pont-l\u2019Abb\u00e9, dans le pays&nbsp;Bigouden. La formation choisit son nom en r\u00e9f\u00e9rence \u00e0 une l\u00e9gende bigoud\u00e8ne. L\u2019id\u00e9e musicale est d\u2019associer les instruments du couple de sonneurs bretons (biniou, bombarde) et les instruments contemporains (accord\u00e9on, guitare folk, basse \u00e9lectrique, <em>pedal-steel<\/em>,&nbsp;etc.). Elle a \u00e9merg\u00e9 dans le cercle celtique de Pont-l\u2019Abb\u00e9 quand des musiciens jouaient des interm\u00e8des entre les diff\u00e9rentes danses. C\u2019est au retour d\u2019une tourn\u00e9e du cercle en Allemagne et au Danemark que Sonerien&nbsp;Du a \u00e9t\u00e9 cr\u00e9\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"l-essor-d-un-groupe-tonique\">L\u2019essor d\u2019un groupe tonique<\/h2>\n\n\n\n<p>Voguant sur une grande \u00ab&nbsp;vague celtique&nbsp;\u00bb, Sonerien&nbsp;Du se lance en 1973 dans une activit\u00e9 fr\u00e9n\u00e9tique. Deux albums 33&nbsp;tours sont publi\u00e9s chez ArFolk. <em>Bal breton<\/em> est vendu \u00e0 6&nbsp;000&nbsp;exemplaires en deux mois (100&nbsp;000&nbsp;exemplaires au final), un succ\u00e8s donc, qui autorise un deuxi\u00e8me disque. Ce Vol.2 comprend le fameux larid\u00e9 \u00ab&nbsp;Jean-Marie&nbsp;\u00bb qui cl\u00f4ture, encore aujourd\u2019hui, la toute fin des prestations des \u00ab&nbsp;Du&nbsp;\u00bb. Le groupe joue de la musique \u00e0 danser, en chantant en fran\u00e7ais ou en breton. Le concept de \u00ab&nbsp;bal breton&nbsp;\u00bb permet d\u2019associer les danses de diff\u00e9rents pays bretons. La composition du groupe \u00e9volue vite. D\u00e8s le d\u00e9but de 1973, Yann-Korentin&nbsp;Ar&nbsp;Gall (1945-1995) passe le relais \u00e0 Yann&nbsp;Goas (1937-2021). Ar&nbsp;Gall pr\u00e9f\u00e9rait une approche traditionnelle de la musique. Sonerien&nbsp;Du inaugure l\u00e0 une pratique originale&nbsp;: le changement en continu de son agencement. Au total, depuis 1972, le groupe s\u2019est appuy\u00e9 sur 23&nbsp;musiciens \u00ab&nbsp;permanents&nbsp;\u00bb (une ann\u00e9e au moins de pr\u00e9sence). Deux autres musiciens arrivent aussi en 1973&nbsp;: le guitariste Didier&nbsp;Quiniou (1954-2014), et Jean-Pierre&nbsp;Le&nbsp;Cam (n\u00e9 en 1949) qui va prendre la basse \u00e9lectrique. Le groupe acquiert une solide r\u00e9putation, avec son entrain et sa force vocale. D\u2019autres groupes sont peut-\u00eatre plus virtuoses, mais Sonerien&nbsp; Du a la p\u00eache.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"452\" src=\"https:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/02\/le_cam_2013.jpg\" alt=\"\" class=\"wp-image-167\" srcset=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/02\/le_cam_2013.jpg 600w, http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/02\/le_cam_2013-300x226.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption>Jean-Pierre Le Cam en&nbsp;2013&nbsp;\u00a9&nbsp;Gilles Simon<\/figcaption><\/figure><\/div>\n\n\n\n<p>En 1975, un troisi\u00e8me album (Volume 3) est enregistr\u00e9 avec le guitariste Dan&nbsp;Ar&nbsp;Braz (n\u00e9 en 1949), et Michel&nbsp;Santangeli (1945-2014) qui a \u00e9t\u00e9 aussi le batteur de Stivell et d\u2019Higelin. Puis, Sonerien&nbsp;Du devient professionnel en 1976. C\u2019est l\u2019un des tout premiers groupes de fest-noz, sinon le premier, \u00e0 faire ce pas. La formation \u00e9volue encore. Didier&nbsp;Quiniou a d\u00e9j\u00e0 quitt\u00e9 la formation car il n\u2019\u00e9tait \u00ab&nbsp;pas fait pour ce m\u00e9tier&nbsp;\u00bb. Dani&nbsp;Tanneau passe le relais \u00e0 Christian&nbsp;Desbordes (n\u00e9 en 1957). \u00catre professionnel permet d\u2019accepter toutes les dates qui sont propos\u00e9es, notamment dans les pays d\u2019Europe du Nord. Sonerien&nbsp;Du d\u00e9bute une nouvelle mani\u00e8re, alternant les festo\u00f9-noz, l\u2019\u00e9t\u00e9 en Bretagne, et les concerts en Allemagne, aux Pays-Bas, etc. Cette activit\u00e9 se traduit en 1977 par le \u00ab&nbsp;record&nbsp;\u00bb du groupe toutes p\u00e9riodes confondues&nbsp;: 126 dates, avec 109&nbsp;festo\u00f9-noz et 27&nbsp;concerts \u00e0 l\u2019\u00e9tranger.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link\" href=\"http:\/\/bcd.bzh\/becedia\/fr\/sonerien-du-50-ans-de-festou-noz-1972-2022\" target=\"_blank\" rel=\"noreferrer noopener\">Lire la suite sur B\u00e9c\u00e9dia<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p>\u00c0 voir \u00e9galement :<\/p>\n<\/div><\/div>\n\n\n<ul class=\"wp-block-latest-posts__list is-grid columns-3 is-style-default wp-block-latest-posts\"><li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"167\" src=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/12\/1972-dastum-300x167.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" style=\"width:100%;height:55.78%;max-width:900px;\" srcset=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/12\/1972-dastum-300x167.png 300w, http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/12\/1972-dastum-768x428.png 768w, http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/12\/1972-dastum.png 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/an-taol-lagad-special-annee-1972-la-naissance-de-dastum\/\">An taol lagad sp\u00e9cial ann\u00e9e 1972 : la naissance de Dastum<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"168\" src=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/09\/1972interceltique-300x168.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" style=\"width:100%;height:56%;max-width:900px;\" srcset=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/09\/1972interceltique-300x168.png 300w, http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/09\/1972interceltique-768x430.png 768w, http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/09\/1972interceltique.png 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/an-taol-lagad-special-annee-1972-le-festival-interceltique\/\">An taol lagad sp\u00e9cial ann\u00e9e 1972 : le festival Interceltique<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"170\" src=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/03\/antaollagadstivell-300x170.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" style=\"width:100%;height:56.63%;max-width:800px;\" srcset=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/03\/antaollagadstivell-300x170.jpg 300w, http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/03\/antaollagadstivell-768x435.jpg 768w, http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/03\/antaollagadstivell.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/an-taol-lagad-special-annee-1972-alan-stivell\/\">An Taol lagad sp\u00e9cial Ann\u00e9e 1972 \u2013 Alan Stivell<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"170\" src=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/03\/An-taol-lagad-Anjela-Duval-300x170.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" style=\"width:100%;height:56.64%;max-width:768px;\" srcset=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/03\/An-taol-lagad-Anjela-Duval-300x170.jpg 300w, http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/03\/An-taol-lagad-Anjela-Duval.jpg 768w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/an-taol-lagad-special-annee-1972-anjela-duval\/\">An Taol lagad sp\u00e9cial Ann\u00e9e 1972 &#8211; Anjela Duval<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"160\" src=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/12\/1972-reveil-culturel-300x160.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" style=\"width:100%;height:53.37%;max-width:1782px;\" srcset=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/12\/1972-reveil-culturel-300x160.jpg 300w, http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/12\/1972-reveil-culturel-1024x546.jpg 1024w, http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/12\/1972-reveil-culturel-768x410.jpg 768w, http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/12\/1972-reveil-culturel-1536x820.jpg 1536w, http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/12\/1972-reveil-culturel-1568x837.jpg 1568w, http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/12\/1972-reveil-culturel.jpg 1782w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/alan-stivell-a-lolympia-en-1972\/\">Alan Stivell \u00e0 l\u2019Olympia en 1972<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"170\" src=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/02\/FIL-300x170.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" style=\"width:100%;height:56.63%;max-width:800px;\" srcset=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/02\/FIL-300x170.jpg 300w, http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/02\/FIL-768x435.jpg 768w, http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/02\/FIL.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/lorient-cinquante-ans-de-fetes-interceltiques\/\">Lorient, cinquante ans de f\u00eates interceltiques<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"170\" src=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/02\/creation-dastum-300x170.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" style=\"width:100%;height:56.63%;max-width:800px;\" srcset=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/02\/creation-dastum-300x170.jpg 300w, http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/02\/creation-dastum-768x435.jpg 768w, http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/02\/creation-dastum.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/la-creation-de-lassociation-dastum-le-23-novembre-1972\/\">Dastum : cr\u00e9ation de l&#8217;association le 23 novembre 1972<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/01\/gweltaz_ar_fur-300x169.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" style=\"width:100%;height:56.25%;max-width:640px;\" srcset=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/01\/gweltaz_ar_fur-300x169.jpg 300w, http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/01\/gweltaz_ar_fur.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/gweltaz-ar-fur-chanteur-engage\/\">Gweltaz Ar Fur, chanteur engag\u00e9<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/01\/yann_goasdoue-300x169.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" style=\"width:100%;height:56.25%;max-width:640px;\" srcset=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/01\/yann_goasdoue-300x169.jpg 300w, http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/01\/yann_goasdoue.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/yann-goasdoue-talabarder-de-diaouled-ar-menez\/\">Yann Goasdoue, talabarder de Diaouled Ar Menez<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"170\" src=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/02\/Servat-2-300x170.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" style=\"width:100%;height:56.63%;max-width:800px;\" srcset=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/02\/Servat-2-300x170.jpg 300w, http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/02\/Servat-2-768x435.jpg 768w, http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/02\/Servat-2.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/temoignage\/la-blanche-hermine-par-gilles-servat\/\">\u00ab La blanche hermine\u00a0\u00bb par Gilles Servat<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"170\" src=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/01\/sonerien-du-300x170.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" style=\"width:100%;height:56.63%;max-width:800px;\" srcset=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/01\/sonerien-du-300x170.jpg 300w, http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/01\/sonerien-du-768x435.jpg 768w, http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/01\/sonerien-du.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/sonerien-du-50-ans-de-festou-noz-1972-2022\/\">Sonerien Du : 50 ans de festo\u00f9-noz (1972-2022)<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"170\" src=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/01\/reveil-2-300x170.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" style=\"width:100%;height:56.63%;max-width:800px;\" srcset=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/01\/reveil-2-300x170.jpg 300w, http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/01\/reveil-2-768x435.jpg 768w, http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/01\/reveil-2.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/le-mouvement-culturel-ou-le-revival-breton\/\">Le Mouvement culturel ou le revival breton<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Auteur : Gilles Simon Cr\u00e9\u00e9 en 1972 au sein du cercle celtique de Pont&nbsp;l\u2019Abb\u00e9, Sonerien&nbsp;Du est le plus vieux groupe de musique bretonne toujours en activit\u00e9. M\u00e9langeant, d\u00e8s le d\u00e9but, sonorit\u00e9s traditionnelles et contemporaines avec \u00e9nergie, il se caract\u00e9rise aussi par une \u00e9volution continue de la composition du groupe qui a eu, en tout, pas&hellip; <a class=\"more-link\" href=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/sonerien-du-50-ans-de-festou-noz-1972-2022\/\">Poursuivre la lecture <span class=\"screen-reader-text\">Sonerien Du : 50 ans de festo\u00f9-noz (1972-2022)<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":656,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[12,3],"tags":[8],"class_list":["post-160","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article","category-reveil-culturel","tag-article","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sonerien Du : 50 ans de festo\u00f9-noz (1972-2022) - La Bretagne en 1972<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/sonerien-du-50-ans-de-festou-noz-1972-2022\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sonerien Du : 50 ans de festo\u00f9-noz (1972-2022) - La Bretagne en 1972\" \/>\n<meta property=\"og:description\" content=\"Auteur : Gilles Simon Cr\u00e9\u00e9 en 1972 au sein du cercle celtique de Pont&nbsp;l\u2019Abb\u00e9, Sonerien&nbsp;Du est le plus vieux groupe de musique bretonne toujours en activit\u00e9. M\u00e9langeant, d\u00e8s le d\u00e9but, sonorit\u00e9s traditionnelles et contemporaines avec \u00e9nergie, il se caract\u00e9rise aussi par une \u00e9volution continue de la composition du groupe qui a eu, en tout, pas&hellip; Poursuivre la lecture Sonerien Du : 50 ans de festo\u00f9-noz (1972-2022)\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/sonerien-du-50-ans-de-festou-noz-1972-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"La Bretagne en 1972\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-20T13:50:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-17T13:47:27+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/01\/sonerien-du.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"453\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Goulven Dauneau\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Goulven Dauneau\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.bcd.bzh\\\/becedia\\\/bretagne-1972\\\/reveil-culturel\\\/sonerien-du-50-ans-de-festou-noz-1972-2022\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.bcd.bzh\\\/becedia\\\/bretagne-1972\\\/reveil-culturel\\\/sonerien-du-50-ans-de-festou-noz-1972-2022\\\/\"},\"author\":{\"name\":\"Goulven Dauneau\",\"@id\":\"\\\/#\\\/schema\\\/person\\\/5fad305ce21fed854df526f903536fd7\"},\"headline\":\"Sonerien Du : 50 ans de festo\u00f9-noz (1972-2022)\",\"datePublished\":\"2022-01-20T13:50:28+00:00\",\"dateModified\":\"2022-02-17T13:47:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.bcd.bzh\\\/becedia\\\/bretagne-1972\\\/reveil-culturel\\\/sonerien-du-50-ans-de-festou-noz-1972-2022\\\/\"},\"wordCount\":652,\"publisher\":{\"@id\":\"\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.bcd.bzh\\\/becedia\\\/bretagne-1972\\\/reveil-culturel\\\/sonerien-du-50-ans-de-festou-noz-1972-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.bcd.bzh\\\/becedia\\\/bretagne-1972\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/sonerien-du.jpg\",\"keywords\":[\"Article\"],\"articleSection\":[\"Article\",\"R\u00e9veil culturel\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.bcd.bzh\\\/becedia\\\/bretagne-1972\\\/reveil-culturel\\\/sonerien-du-50-ans-de-festou-noz-1972-2022\\\/\",\"url\":\"http:\\\/\\\/www.bcd.bzh\\\/becedia\\\/bretagne-1972\\\/reveil-culturel\\\/sonerien-du-50-ans-de-festou-noz-1972-2022\\\/\",\"name\":\"Sonerien Du : 50 ans de festo\u00f9-noz (1972-2022) - La Bretagne en 1972\",\"isPartOf\":{\"@id\":\"\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.bcd.bzh\\\/becedia\\\/bretagne-1972\\\/reveil-culturel\\\/sonerien-du-50-ans-de-festou-noz-1972-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.bcd.bzh\\\/becedia\\\/bretagne-1972\\\/reveil-culturel\\\/sonerien-du-50-ans-de-festou-noz-1972-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.bcd.bzh\\\/becedia\\\/bretagne-1972\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/sonerien-du.jpg\",\"datePublished\":\"2022-01-20T13:50:28+00:00\",\"dateModified\":\"2022-02-17T13:47:27+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.bcd.bzh\\\/becedia\\\/bretagne-1972\\\/reveil-culturel\\\/sonerien-du-50-ans-de-festou-noz-1972-2022\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.bcd.bzh\\\/becedia\\\/bretagne-1972\\\/reveil-culturel\\\/sonerien-du-50-ans-de-festou-noz-1972-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/www.bcd.bzh\\\/becedia\\\/bretagne-1972\\\/reveil-culturel\\\/sonerien-du-50-ans-de-festou-noz-1972-2022\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.bcd.bzh\\\/becedia\\\/bretagne-1972\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/sonerien-du.jpg\",\"contentUrl\":\"http:\\\/\\\/www.bcd.bzh\\\/becedia\\\/bretagne-1972\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/sonerien-du.jpg\",\"width\":800,\"height\":453,\"caption\":\"Mus\u00e9e de Bretagne, Collection Arts graphiques\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.bcd.bzh\\\/becedia\\\/bretagne-1972\\\/reveil-culturel\\\/sonerien-du-50-ans-de-festou-noz-1972-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\\\/\\\/www.bcd.bzh\\\/becedia\\\/bretagne-1972\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sonerien Du : 50 ans de festo\u00f9-noz (1972-2022)\"}]},{\"@type\":\"WebSite\",\"@id\":\"\\\/#website\",\"url\":\"\\\/\",\"name\":\"La Bretagne en 1972\",\"description\":\"\",\"publisher\":{\"@id\":\"\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"\\\/#organization\",\"name\":\"La Bretagne en 1972\",\"url\":\"\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.bcd.bzh\\\/becedia\\\/bretagne-1972\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/site-logo.svg\",\"contentUrl\":\"http:\\\/\\\/www.bcd.bzh\\\/becedia\\\/bretagne-1972\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/site-logo.svg\",\"width\":309,\"height\":107,\"caption\":\"La Bretagne en 1972\"},\"image\":{\"@id\":\"\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"\\\/#\\\/schema\\\/person\\\/5fad305ce21fed854df526f903536fd7\",\"name\":\"Goulven Dauneau\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1cda8175f8100219562fbbfc90c7eeacd6c2519ed220325274deb7e8a443d55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1cda8175f8100219562fbbfc90c7eeacd6c2519ed220325274deb7e8a443d55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1cda8175f8100219562fbbfc90c7eeacd6c2519ed220325274deb7e8a443d55?s=96&d=mm&r=g\",\"caption\":\"Goulven Dauneau\"},\"url\":\"http:\\\/\\\/www.bcd.bzh\\\/becedia\\\/bretagne-1972\\\/author\\\/gdauneau\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sonerien Du : 50 ans de festo\u00f9-noz (1972-2022) - La Bretagne en 1972","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/sonerien-du-50-ans-de-festou-noz-1972-2022\/","og_locale":"fr_FR","og_type":"article","og_title":"Sonerien Du : 50 ans de festo\u00f9-noz (1972-2022) - La Bretagne en 1972","og_description":"Auteur : Gilles Simon Cr\u00e9\u00e9 en 1972 au sein du cercle celtique de Pont&nbsp;l\u2019Abb\u00e9, Sonerien&nbsp;Du est le plus vieux groupe de musique bretonne toujours en activit\u00e9. M\u00e9langeant, d\u00e8s le d\u00e9but, sonorit\u00e9s traditionnelles et contemporaines avec \u00e9nergie, il se caract\u00e9rise aussi par une \u00e9volution continue de la composition du groupe qui a eu, en tout, pas&hellip; Poursuivre la lecture Sonerien Du : 50 ans de festo\u00f9-noz (1972-2022)","og_url":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/sonerien-du-50-ans-de-festou-noz-1972-2022\/","og_site_name":"La Bretagne en 1972","article_published_time":"2022-01-20T13:50:28+00:00","article_modified_time":"2022-02-17T13:47:27+00:00","og_image":[{"width":800,"height":453,"url":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/01\/sonerien-du.jpg","type":"image\/jpeg"}],"author":"Goulven Dauneau","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Goulven Dauneau","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/sonerien-du-50-ans-de-festou-noz-1972-2022\/#article","isPartOf":{"@id":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/sonerien-du-50-ans-de-festou-noz-1972-2022\/"},"author":{"name":"Goulven Dauneau","@id":"\/#\/schema\/person\/5fad305ce21fed854df526f903536fd7"},"headline":"Sonerien Du : 50 ans de festo\u00f9-noz (1972-2022)","datePublished":"2022-01-20T13:50:28+00:00","dateModified":"2022-02-17T13:47:27+00:00","mainEntityOfPage":{"@id":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/sonerien-du-50-ans-de-festou-noz-1972-2022\/"},"wordCount":652,"publisher":{"@id":"\/#organization"},"image":{"@id":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/sonerien-du-50-ans-de-festou-noz-1972-2022\/#primaryimage"},"thumbnailUrl":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/01\/sonerien-du.jpg","keywords":["Article"],"articleSection":["Article","R\u00e9veil culturel"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/sonerien-du-50-ans-de-festou-noz-1972-2022\/","url":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/sonerien-du-50-ans-de-festou-noz-1972-2022\/","name":"Sonerien Du : 50 ans de festo\u00f9-noz (1972-2022) - La Bretagne en 1972","isPartOf":{"@id":"\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/sonerien-du-50-ans-de-festou-noz-1972-2022\/#primaryimage"},"image":{"@id":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/sonerien-du-50-ans-de-festou-noz-1972-2022\/#primaryimage"},"thumbnailUrl":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/01\/sonerien-du.jpg","datePublished":"2022-01-20T13:50:28+00:00","dateModified":"2022-02-17T13:47:27+00:00","breadcrumb":{"@id":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/sonerien-du-50-ans-de-festou-noz-1972-2022\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/sonerien-du-50-ans-de-festou-noz-1972-2022\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/sonerien-du-50-ans-de-festou-noz-1972-2022\/#primaryimage","url":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/01\/sonerien-du.jpg","contentUrl":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/01\/sonerien-du.jpg","width":800,"height":453,"caption":"Mus\u00e9e de Bretagne, Collection Arts graphiques"},{"@type":"BreadcrumbList","@id":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/reveil-culturel\/sonerien-du-50-ans-de-festou-noz-1972-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/"},{"@type":"ListItem","position":2,"name":"Sonerien Du : 50 ans de festo\u00f9-noz (1972-2022)"}]},{"@type":"WebSite","@id":"\/#website","url":"\/","name":"La Bretagne en 1972","description":"","publisher":{"@id":"\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"\/#organization","name":"La Bretagne en 1972","url":"\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"\/#\/schema\/logo\/image\/","url":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/01\/site-logo.svg","contentUrl":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-content\/uploads\/2022\/01\/site-logo.svg","width":309,"height":107,"caption":"La Bretagne en 1972"},"image":{"@id":"\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"\/#\/schema\/person\/5fad305ce21fed854df526f903536fd7","name":"Goulven Dauneau","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a1cda8175f8100219562fbbfc90c7eeacd6c2519ed220325274deb7e8a443d55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a1cda8175f8100219562fbbfc90c7eeacd6c2519ed220325274deb7e8a443d55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a1cda8175f8100219562fbbfc90c7eeacd6c2519ed220325274deb7e8a443d55?s=96&d=mm&r=g","caption":"Goulven Dauneau"},"url":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/author\/gdauneau\/"}]}},"_links":{"self":[{"href":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-json\/wp\/v2\/posts\/160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-json\/wp\/v2\/comments?post=160"}],"version-history":[{"count":8,"href":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-json\/wp\/v2\/posts\/160\/revisions"}],"predecessor-version":[{"id":991,"href":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-json\/wp\/v2\/posts\/160\/revisions\/991"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-json\/wp\/v2\/media\/656"}],"wp:attachment":[{"href":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-json\/wp\/v2\/media?parent=160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-json\/wp\/v2\/categories?post=160"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.bcd.bzh\/becedia\/bretagne-1972\/wp-json\/wp\/v2\/tags?post=160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}